{"id":7239,"date":"2016-06-12T21:28:35","date_gmt":"2016-06-12T18:28:35","guid":{"rendered":"http:\/\/ades.erciyes.edu.tr\/?page_id=7239"},"modified":"2018-05-27T17:03:57","modified_gmt":"2018-05-27T14:03:57","slug":"ades-2-photos","status":"publish","type":"page","link":"https:\/\/ades.erciyes.edu.tr\/en\/ades-2-photos\/","title":{"rendered":"Ades 2 &#8211; Photos"},"content":{"rendered":"<style type=\"text\/css\"> \n#cmsmasters_row_6a046eca803e4 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a046eca803e4 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 50px; \n} \n\n \n#cmsmasters_divider_6a046eca815cd { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:solid; \n\tpadding-top:50px; \n\tmargin-bottom:50px; \n} \n\n\t\t\t\t#cmsmasters_gallery_6a046eca825b4 .cmsmasters_gallery {\n\t\t\t\t\tmargin:0 0 0 -10px;\n\t\t\t\t}\n\t\t\t\t\n\t\t\t\t#cmsmasters_gallery_6a046eca825b4 .cmsmasters_gallery .cmsmasters_gallery_item {\n\t\t\t\t\tpadding:0 0 10px 10px;\n\t\t\t\t}\n\t\t\t \n#cmsmasters_divider_6a046eca9f3da { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:solid; \n\tpadding-top:50px; \n\tmargin-bottom:50px; \n} \n \n#cmsmasters_row_6a046eca9fb9d .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a046eca9fb9d .cmsmasters_row_outer_parent { \n\tpadding-bottom: 50px; \n} \n\n \n#cmsmasters_divider_6a046ecaa0c9b { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:solid; \n\tpadding-top:50px; \n\tmargin-bottom:50px; \n} \n\n\t\t\t\t#cmsmasters_gallery_6a046ecaa1eeb .cmsmasters_gallery {\n\t\t\t\t\tmargin:0 0 0 -10px;\n\t\t\t\t}\n\t\t\t\t\n\t\t\t\t#cmsmasters_gallery_6a046ecaa1eeb .cmsmasters_gallery .cmsmasters_gallery_item {\n\t\t\t\t\tpadding:0 0 10px 10px;\n\t\t\t\t}\n\t\t\t \n#cmsmasters_divider_6a046ecaa89d6 { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:solid; \n\tpadding-top:50px; \n\tmargin-bottom:50px; \n} \n<\/style><p><div id=\"cmsmasters_row_6a046eca9fb9d\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n\n<div id=\"cmsmasters_divider_6a046ecaa0c9b\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center\"><\/div><div id=\"cmsmasters_gallery_6a046ecaa1eeb\" class=\"cmsmasters_gallery_wrap\"><ul class=\"cmsmasters_gallery cmsmasters_3 cmsmasters_more_items_loader\"><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_001.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_001.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_001.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_001-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_001-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_001-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_001-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_001-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_001-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_002.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_002.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_002.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_002-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_002-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_002-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_002-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_002-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_002-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_003.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_003.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_003.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_003-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_003-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_003-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_003-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_003-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_003-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_004.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_004.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_004.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_004-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_004-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_004-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_004-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_004-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_004-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_005.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_005.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_005.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_005-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_005-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_005-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_005-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_005-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_005-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_006.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_006.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_006.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_006-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_006-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_006-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_006-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_006-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_006-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_007.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_007.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_007.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_007-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_007-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_007-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_007-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_007-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_007-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_008.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_008.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_008.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_008-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_008-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_008-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_008-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_008-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_008-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_009.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_009.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_009.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_009-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_009-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_009-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_009-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_009-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_009-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_010.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_010.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_010.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_010-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_010-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_010-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_010-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_010-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_010-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_011.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_011.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_011.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_011-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_011-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_011-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_011-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_011-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_011-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_012.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_012.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_012.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_012-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_012-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_012-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_012-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_012-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_012-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_013.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"509\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_013.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_013.jpg 509w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_013-199x300.jpg 199w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_014.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_014.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_014.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_014-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_014-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_014-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_014-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_014-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_014-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_015.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_015.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_015.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_015-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_015-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_015-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_015-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_015-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_015-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_016.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"509\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_016.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_016.jpg 509w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_016-199x300.jpg 199w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_017.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_017.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_017.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_017-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_017-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_017-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_017-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_017-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_017-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_018.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"509\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_018.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_018.jpg 509w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_018-199x300.jpg 199w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_019.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_019.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_019.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_019-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_019-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_019-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_019-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_019-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_019-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_020.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_020.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_020.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_020-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_020-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_020-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_020-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_020-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_020-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_021.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_021.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_021.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_021-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_021-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_021-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_021-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_021-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_021-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_022.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_022.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_022.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_022-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_022-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_022-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_022-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_022-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_022-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_023.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_023.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_023.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_023-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_023-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_023-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_023-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_023-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_023-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_024.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_024.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_024.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_024-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_024-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_024-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_024-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_024-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_024-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_025.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_025.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_025.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_025-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_025-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_025-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_025-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_025-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_025-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_026.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_026.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_026.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_026-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_026-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_026-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_026-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_026-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_026-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_027.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"509\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_027.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_027.jpg 509w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_027-199x300.jpg 199w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_028.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_028.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_028.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_028-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_028-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_028-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_028-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_028-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_028-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_029.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_029.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_029.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_029-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_029-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_029-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_029-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_029-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_029-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_030.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_030.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_030.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_030-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_030-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_030-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_030-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_030-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_030-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_031.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_031.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_031.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_031-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_031-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_031-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_031-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_031-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_031-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_032.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_032.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_032.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_032-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_032-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_032-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_032-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_032-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_032-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_033.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_033.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_033.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_033-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_033-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_033-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_033-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_033-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_033-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_034.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_034.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_034.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_034-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_034-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_034-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_034-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_034-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_034-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_035.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_035.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_035.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_035-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_035-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_035-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_035-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_035-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_035-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_036.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_036.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_036.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_036-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_036-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_036-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_036-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_036-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_036-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_037.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_037.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_037.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_037-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_037-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_037-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_037-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_037-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_037-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_038.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_038.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_038.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_038-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_038-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_038-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_038-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_038-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_038-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_039.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_039.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_039.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_039-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_039-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_039-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_039-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_039-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_039-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_040.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_040.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_040.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_040-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_040-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_040-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_040-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_040-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_040-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_041.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_041.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_041.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_041-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_041-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_041-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_041-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_041-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_041-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_042.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_042.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_042.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_042-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_042-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_042-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_042-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_042-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_042-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_043.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_043.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_043.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_043-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_043-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_043-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_043-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_043-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_043-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_044.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_044.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_044.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_044-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_044-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_044-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_044-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_044-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_044-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_045.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_045.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_045.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_045-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_045-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_045-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_045-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_045-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_045-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_046.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_046.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_046.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_046-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_046-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_046-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_046-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_046-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_046-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_047.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_047.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_047.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_047-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_047-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_047-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_047-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_047-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_047-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_048.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_048.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_048.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_048-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_048-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_048-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_048-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_048-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_048-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_049.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_049.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_049.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_049-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_049-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_049-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_049-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_049-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_049-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_050.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_050.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_050.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_050-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_050-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_050-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_050-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_050-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_050-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_051.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_051.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_051.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_051-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_051-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_051-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_051-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_051-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_051-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_052.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_052.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_052.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_052-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_052-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_052-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_052-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_052-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_052-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_053.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_053.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_053.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_053-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_053-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_053-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_053-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_053-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_053-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_054.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_054.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_054.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_054-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_054-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_054-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_054-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_054-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_054-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_055.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_055.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_055.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_055-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_055-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_055-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_055-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_055-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_055-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_056.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_056.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_056.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_056-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_056-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_056-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_056-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_056-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_056-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_057.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_057.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_057.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_057-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_057-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_057-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_057-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_057-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_057-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_058.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_058.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_058.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_058-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_058-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_058-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_058-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_058-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_058-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_059.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_059.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_059.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_059-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_059-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_059-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_059-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_059-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_059-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_060.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_060.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_060.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_060-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_060-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_060-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_060-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_060-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_060-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_061.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_061.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_061.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_061-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_061-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_061-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_061-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_061-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_061-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_062.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_062.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_062.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_062-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_062-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_062-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_062-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_062-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_062-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_063.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_063.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_063.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_063-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_063-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_063-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_063-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_063-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_063-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_064.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_064.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_064.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_064-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_064-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_064-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_064-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_064-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_064-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_065.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_065.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_065.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_065-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_065-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_065-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_065-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_065-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_065-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_066.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_066.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_066.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_066-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_066-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_066-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_066-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_066-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_066-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_067.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_067.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_067.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_067-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_067-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_067-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_067-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_067-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_067-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_068.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1159\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_068.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_068.jpg 1159w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_068-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_068-768x509.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_068-1024x679.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_068-600x398.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_068-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_068-860x570.jpg 860w\" sizes=\"(max-width: 1159px) 100vw, 1159px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_069.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"509\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_069.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_069.jpg 509w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_069-199x300.jpg 199w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_070.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"509\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_070.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_070.jpg 509w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_070-199x300.jpg 199w\" sizes=\"(max-width: 509px) 100vw, 509px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_071.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_071.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_071.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_071-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_071-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_071-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_071-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_071-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_071-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_072.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_072.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_072.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_072-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_072-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_072-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_072-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_072-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_072-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_073.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_073.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_073.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_073-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_073-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_073-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_073-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_073-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_073-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_074.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_074.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_074.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_074-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_074-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_074-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_074-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_074-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_074-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_075.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_075.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_075.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_075-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_075-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_075-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_075-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_075-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_075-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_076.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_076.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_076.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_076-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_076-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_076-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_076-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_076-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_076-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_077.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_077.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_077.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_077-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_077-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_077-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_077-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_077-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_077-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_078.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_078.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_078.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_078-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_078-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_078-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_078-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_078-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_078-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_079.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_079.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_079.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_079-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_079-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_079-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_079-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_079-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_079-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_080.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_080.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_080.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_080-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_080-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_080-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_080-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_080-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_080-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_081.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_081.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_081.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_081-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_081-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_081-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_081-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_081-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_081-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_082.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_082.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_082.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_082-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_082-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_082-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_082-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_082-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_082-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_083.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_083.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_083.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_083-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_083-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_083-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_083-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_083-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_083-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_084.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_084.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_084.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_084-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_084-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_084-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_084-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_084-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_084-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_085.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_085.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_085.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_085-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_085-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_085-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_085-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_085-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_085-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_086.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_086.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_086.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_086-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_086-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_086-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_086-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_086-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_086-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_087.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_087.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_087.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_087-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_087-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_087-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_087-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_087-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_087-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_088.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_088.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_088.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_088-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_088-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_088-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_088-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_088-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_088-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_089.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_089.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_089.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_089-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_089-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_089-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_089-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_089-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_089-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_090.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_090.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_090.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_090-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_090-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_090-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_090-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_090-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_090-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_091.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_091.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_091.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_091-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_091-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_091-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_091-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_091-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_091-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_092.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_092.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_092.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_092-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_092-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_092-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_092-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_092-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_092-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_093.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_093.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_093.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_093-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_093-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_093-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_093-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_093-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_093-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_094.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_094.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_094.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_094-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_094-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_094-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_094-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_094-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_094-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_095.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_095.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_095.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_095-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_095-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_095-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_095-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_095-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_095-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_096.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_096.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_096.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_096-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_096-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_096-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_096-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_096-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_096-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_097.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_097.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_097.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_097-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_097-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_097-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_097-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_097-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_097-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_098.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_098.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_098.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_098-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_098-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_098-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_098-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_098-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_098-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_099.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_099.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_099.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_099-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_099-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_099-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_099-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_099-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_099-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_100.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_100.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_100.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_100-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_100-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_100-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_100-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_100-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_100-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_101.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_101.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_101.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_101-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_101-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_101-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_101-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_101-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_101-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_102.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_102.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_102.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_102-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_102-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_102-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_102-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_102-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_102-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_103.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_103.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_103.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_103-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_103-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_103-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_103-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_103-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_103-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_104.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_104.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_104.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_104-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_104-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_104-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_104-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_104-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_104-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_105.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_105.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_105.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_105-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_105-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_105-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_105-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_105-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_105-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_106.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_106.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_106.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_106-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_106-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_106-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_106-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_106-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_106-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_107.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_107.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_107.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_107-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_107-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_107-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_107-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_107-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_107-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_108.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_108.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_108.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_108-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_108-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_108-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_108-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_108-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_108-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_109.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_109.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_109.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_109-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_109-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_109-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_109-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_109-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_109-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_110.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_110.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_110.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_110-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_110-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_110-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_110-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_110-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_110-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_111.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_111.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_111.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_111-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_111-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_111-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_111-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_111-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_111-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_112.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_112.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_112.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_112-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_112-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_112-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_112-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_112-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_112-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_113.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_113.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_113.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_113-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_113-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_113-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_113-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_113-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_113-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_114.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_114.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_114.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_114-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_114-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_114-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_114-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_114-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_114-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_115.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"512\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_115.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_115.jpg 512w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_115-200x300.jpg 200w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_116.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"512\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_116.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_116.jpg 512w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_116-200x300.jpg 200w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_117.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"512\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_117.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_117.jpg 512w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_117-200x300.jpg 200w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_118.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"512\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_118.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_118.jpg 512w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_118-200x300.jpg 200w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_119.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"512\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_119.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_119.jpg 512w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_119-200x300.jpg 200w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_120.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_120.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_120.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_120-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_120-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_120-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_120-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_120-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_120-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_121.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_121.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_121.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_121-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_121-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_121-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_121-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_121-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_121-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_122.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_122.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_122.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_122-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_122-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_122-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_122-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_122-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_122-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_123.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_123.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_123.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_123-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_123-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_123-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_123-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_123-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_123-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_124.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_124.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_124.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_124-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_124-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_124-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_124-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_124-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_124-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_126.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_126.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_126.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_126-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_126-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_126-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_126-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_126-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_126-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_127.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_127.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_127.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_127-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_127-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_127-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_127-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_127-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_127-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_128.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_128.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_128.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_128-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_128-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_128-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_128-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_128-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_128-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_129.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_129.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_129.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_129-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_129-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_129-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_129-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_129-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_129-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_130.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_130.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_130.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_130-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_130-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_130-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_130-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_130-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_130-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_131.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_131.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_131.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_131-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_131-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_131-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_131-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_131-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_131-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_132.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_132.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_132.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_132-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_132-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_132-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_132-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_132-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_132-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_133.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_133.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_133.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_133-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_133-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_133-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_133-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_133-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_133-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_134.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_134.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_134.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_134-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_134-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_134-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_134-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_134-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_134-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_135.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_135.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_135.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_135-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_135-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_135-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_135-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_135-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_135-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_136.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_136.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_136.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_136-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_136-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_136-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_136-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_136-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_136-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_137.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_137.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_137.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_137-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_137-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_137-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_137-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_137-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_137-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_138.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_138.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_138.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_138-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_138-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_138-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_138-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_138-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_138-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_139.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_139.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_139.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_139-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_139-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_139-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_139-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_139-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_139-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_140.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_140.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_140.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_140-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_140-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_140-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_140-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_140-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_140-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_141.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1152\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_141.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_141.jpg 1152w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_141-300x200.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_141-768x512.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_141-1024x683.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_141-600x400.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_141-580x387.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_141-860x573.jpg 860w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/><\/a><\/figure><\/li><li class=\"cmsmasters_gallery_item\"><figure><a href=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_142.jpg\" rel=\"ilightbox[6a046ecaa1eeb]\"><img width=\"1160\" height=\"768\" src=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_142.jpg\" class=\"attachment-full size-full\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_142.jpg 1160w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_142-300x199.jpg 300w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_142-768x508.jpg 768w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_142-1024x678.jpg 1024w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_142-600x397.jpg 600w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_142-580x384.jpg 580w, https:\/\/ades.erciyes.edu.tr\/wp-content\/uploads\/2018\/05\/ADES2_142-860x569.jpg 860w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure><\/li><\/ul><script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function () {\n\t\t\t\t\t(function ($) {\n\t\t\t\t\t\tif ($('#cmsmasters_gallery_6a046ecaa1eeb').find('.cmsmasters_gallery_item').length == '0') {\n\t\t\t\t\t\t\treturn false;\n\t\t\t\t\t\t}\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\tstartGallery( \n\t\t\t\t\t\t\t'6a046ecaa1eeb', \n\t\t\t\t\t\t\t'masonry', \n\t\t\t\t\t\t\t'false', \n\t\t\t\t\t\t\t'false' \n\t\t\t\t\t\t);\n\t\t\t\t\t} )(jQuery);\n\t\t\t\t} );\n\t\t\t<\/script>\n\t\t\t<\/div>\n<div id=\"cmsmasters_divider_6a046ecaa89d6\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/ades.erciyes.edu.tr\/en\/wp-json\/wp\/v2\/pages\/7239"}],"collection":[{"href":"https:\/\/ades.erciyes.edu.tr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ades.erciyes.edu.tr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ades.erciyes.edu.tr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ades.erciyes.edu.tr\/en\/wp-json\/wp\/v2\/comments?post=7239"}],"version-history":[{"count":18,"href":"https:\/\/ades.erciyes.edu.tr\/en\/wp-json\/wp\/v2\/pages\/7239\/revisions"}],"predecessor-version":[{"id":9669,"href":"https:\/\/ades.erciyes.edu.tr\/en\/wp-json\/wp\/v2\/pages\/7239\/revisions\/9669"}],"wp:attachment":[{"href":"https:\/\/ades.erciyes.edu.tr\/en\/wp-json\/wp\/v2\/media?parent=7239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}